{"id":3489,"count":1,"description":"","link":"https:\/\/progressions.prsa.org\/index.php\/tag\/expectationsvsreality\/","name":"expectationsvsreality","slug":"expectationsvsreality","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/progressions.prsa.org\/index.php\/tag\/expectationsvsreality\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/3489\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/progressions.prsa.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progressions.prsa.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/tag\\\/expectationsvsreality\\\/#listItem\",\"name\":\"expectationsvsreality\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/tag\\\/expectationsvsreality\\\/#listItem\",\"position\":2,\"name\":\"expectationsvsreality\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/progressions.prsa.org#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/3489\\\/#collectionpage\",\"url\":\"https:\\\/\\\/progressions.prsa.org\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/3489\\\/\",\"name\":\"expectationsvsreality - Progressions\",\"inLanguage\":\"en\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/3489\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/#organization\",\"name\":\"Progressions\",\"description\":\"Advancing the Profession and the Future Professional\",\"url\":\"https:\\\/\\\/progressions.prsa.org\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/#website\",\"url\":\"https:\\\/\\\/progressions.prsa.org\\\/\",\"name\":\"Progressions\",\"description\":\"Advancing the Profession and the Future Professional\",\"inLanguage\":\"en\",\"publisher\":{\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"expectationsvsreality - Progressions","description":"","canonical_url":"https:\/\/progressions.prsa.org\/index.php\/tag\/expectationsvsreality\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/progressions.prsa.org\/wp-json\/wp\/v2\/tags\/3489\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/progressions.prsa.org#listItem","position":1,"name":"Home","item":"https:\/\/progressions.prsa.org","nextItem":{"@type":"ListItem","@id":"https:\/\/progressions.prsa.org\/index.php\/tag\/expectationsvsreality\/#listItem","name":"expectationsvsreality"}},{"@type":"ListItem","@id":"https:\/\/progressions.prsa.org\/index.php\/tag\/expectationsvsreality\/#listItem","position":2,"name":"expectationsvsreality","previousItem":{"@type":"ListItem","@id":"https:\/\/progressions.prsa.org#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/progressions.prsa.org\/wp-json\/wp\/v2\/tags\/3489\/#collectionpage","url":"https:\/\/progressions.prsa.org\/wp-json\/wp\/v2\/tags\/3489\/","name":"expectationsvsreality - Progressions","inLanguage":"en","isPartOf":{"@id":"https:\/\/progressions.prsa.org\/#website"},"breadcrumb":{"@id":"https:\/\/progressions.prsa.org\/wp-json\/wp\/v2\/tags\/3489\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/progressions.prsa.org\/#organization","name":"Progressions","description":"Advancing the Profession and the Future Professional","url":"https:\/\/progressions.prsa.org\/"},{"@type":"WebSite","@id":"https:\/\/progressions.prsa.org\/#website","url":"https:\/\/progressions.prsa.org\/","name":"Progressions","description":"Advancing the Profession and the Future Professional","inLanguage":"en","publisher":{"@id":"https:\/\/progressions.prsa.org\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/progressions.prsa.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\texpectationsvsreality\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/progressions.prsa.org"},{"label":"expectationsvsreality","link":"https:\/\/progressions.prsa.org\/index.php\/tag\/expectationsvsreality\/"}],"_links":{"self":[{"href":"https:\/\/progressions.prsa.org\/index.php\/wp-json\/wp\/v2\/tags\/3489"}],"collection":[{"href":"https:\/\/progressions.prsa.org\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/progressions.prsa.org\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/progressions.prsa.org\/index.php\/wp-json\/wp\/v2\/posts?tags=3489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}