{"id":13585,"date":"2025-08-01T14:47:39","date_gmt":"2025-08-01T18:47:39","guid":{"rendered":"https:\/\/progressions.prsa.org\/?p=13585"},"modified":"2025-08-01T14:47:40","modified_gmt":"2025-08-01T18:47:40","slug":"voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach","status":"publish","type":"post","link":"https:\/\/progressions.prsa.org\/index.php\/2025\/08\/01\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\/","title":{"rendered":"Voces de PRSA: Perspectivas de la Secci\u00f3n de Nuevos Profesionales \u2013 Mariola Lach"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/progressions.prsa.org\/wp-content\/uploads\/2025\/08\/PRSSA-Progressions-Blog-Headers-PRSSA-Voices-Insights-From-the-New-Professionals-Section-Mariola-Lach-Spanish-Version-1024x576.png\" alt=\"\" class=\"wp-image-13586\" srcset=\"https:\/\/progressions.prsa.org\/wp-content\/uploads\/2025\/08\/PRSSA-Progressions-Blog-Headers-PRSSA-Voices-Insights-From-the-New-Professionals-Section-Mariola-Lach-Spanish-Version-1024x576.png 1024w, https:\/\/progressions.prsa.org\/wp-content\/uploads\/2025\/08\/PRSSA-Progressions-Blog-Headers-PRSSA-Voices-Insights-From-the-New-Professionals-Section-Mariola-Lach-Spanish-Version-300x169.png 300w, https:\/\/progressions.prsa.org\/wp-content\/uploads\/2025\/08\/PRSSA-Progressions-Blog-Headers-PRSSA-Voices-Insights-From-the-New-Professionals-Section-Mariola-Lach-Spanish-Version-768x432.png 768w, https:\/\/progressions.prsa.org\/wp-content\/uploads\/2025\/08\/PRSSA-Progressions-Blog-Headers-PRSSA-Voices-Insights-From-the-New-Professionals-Section-Mariola-Lach-Spanish-Version-1536x864.png 1536w, https:\/\/progressions.prsa.org\/wp-content\/uploads\/2025\/08\/PRSSA-Progressions-Blog-Headers-PRSSA-Voices-Insights-From-the-New-Professionals-Section-Mariola-Lach-Spanish-Version-2048x1152.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Nombre<\/strong><\/p>\n\n\n\n<p>Mariola Lach<\/p>\n\n\n\n<p><strong>Cargo&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p>Ejecutiva de Cuentas, Crisis e Issues en Zeno Group<\/p>\n\n\n\n<p><strong>Rol dentro de la Secci\u00f3n de Nuevos Profesionales de PRSA&nbsp;<\/strong><\/p>\n\n\n\n<p>Chair de la Secci\u00f3n<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 te inspir\u00f3 a involucrarte con PRSA y c\u00f3mo ha evolucionado tu trayectoria dentro de la organizaci\u00f3n?&nbsp;<\/strong><\/p>\n\n\n\n<p>Cuando comenc\u00e9 mi carrera en relaciones p\u00fablicas, me di cuenta de que a\u00fan hab\u00eda mucho que no sab\u00eda. Supuse que muchos otros nuevos profesionales probablemente ten\u00edan las mismas dudas, y eso me inspir\u00f3 a ayudarlos creando programas \u00fatiles. Dise\u00f1\u00e9 programas y colabor\u00e9 con contenido para redes sociales durante dos a\u00f1os antes de convertirme en Chair este a\u00f1o.<\/p>\n\n\n\n<p><strong>\u00bfEn qu\u00e9 consiste tu rol dentro de la Secci\u00f3n de Nuevos Profesionales de PRSA?<\/strong><\/p>\n\n\n\n<p>Como Chair de la Secci\u00f3n de Nuevos Profesionales de PRSA, lidero el comit\u00e9 nacional dedicado a apoyar a profesionales con menos de cinco a\u00f1os de experiencia en relaciones p\u00fablicas. Trabajo de cerca con nuestra junta ejecutiva, brind\u00e1ndoles apoyo y orientaci\u00f3n para que tengan \u00e9xito en sus roles y as\u00ed podamos ofrecer constantemente un valor significativo a nuestros miembros.<\/p>\n\n\n\n<p><strong>\u00bfC\u00f3mo fue tu transici\u00f3n a la industria de las relaciones p\u00fablicas? Como alguien que no sigui\u00f3 un camino tradicional, \u00bfcu\u00e1les fueron algunas de las lecciones m\u00e1s importantes que aprendiste al principio?<\/strong><\/p>\n\n\n\n<p>Al principio hubo definitivamente una curva de aprendizaje, pero aprend\u00ed a apoyarme en las habilidades que ya ten\u00eda y a utilizar todos los recursos disponibles para cerrar las brechas. Tuve la suerte de contar con personas que me apoyaron y aconsejaron en el camino\u2014jugaron un papel fundamental en mi crecimiento. La lecci\u00f3n m\u00e1s grande fue mantenerme constante, pero flexible con mis objetivos.<\/p>\n\n\n\n<p><strong>Si pudieras volver al momento en que empezaste a explorar el mundo de las relaciones p\u00fablicas, \u00bfqu\u00e9 te hubiera gustado saber sobre la profesi\u00f3n o sobre PRSA?&nbsp;<\/strong><\/p>\n\n\n\n<p>Me hubiera gustado saber cu\u00e1ntos recursos existen y lo amplia que es la industria. Incluso ahora, sigo aprendiendo cosas nuevas sobre el sector.<\/p>\n\n\n\n<p><strong>\u00bfC\u00f3mo te ha ayudado formar parte de PRSA y de la Secci\u00f3n de Nuevos Profesionales a crecer profesionalmente y a navegar las primeras etapas de tu carrera?&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p>Estoy realmente agradecida con PRSA por todo lo que me ha ayudado, pero como en todo, depende de lo que uno haga con las oportunidades. Los recursos que ofrece PRSA\u2014como los seminarios web que me ayudaron a desarrollar habilidades y Mentor Connect, que me permiti\u00f3 conectar con profesionales experimentados\u2014fueron fundamentales antes de hacer la transici\u00f3n, y a\u00fan lo son hoy en d\u00eda.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 consejo les dar\u00edas a los miembros de PRSSA que est\u00e1n por comenzar sus carreras?<\/strong><\/p>\n\n\n\n<p>\u00a1Hay much\u00edsimos recursos disponibles para ayudarte a iniciar tu carrera; aprov\u00e9chalos! Invol\u00facrate y conecta con otras personas; las relaciones que construyas pueden durar toda la vida y ser beneficiosas tanto para ti como para los dem\u00e1s. Aprovecha las habilidades que ya tienes y util\u00edzalas como punto de partida para tu nueva carrera.<\/p>\n\n\n\n<p><strong>Por \u00faltimo, \u00bfc\u00f3mo pueden los miembros de PRSSA conectar contigo o seguir tu trabajo?<\/strong><\/p>\n\n\n\n<p>Los miembros de PRSSA pueden conectar conmigo a trav\u00e9s de <a href=\"https:\/\/www.linkedin.com\/in\/mariolalach\/\">LinkedIn<\/a>. Estar\u00eda encantada de conversar o responder cualquier pregunta.\u00a0<\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"681\" height=\"1024\" src=\"https:\/\/progressions.prsa.org\/wp-content\/uploads\/2025\/08\/Mariola-Lach-Headshot-1-681x1024.jpg\" alt=\"\" class=\"wp-image-13587 size-full\" srcset=\"https:\/\/progressions.prsa.org\/wp-content\/uploads\/2025\/08\/Mariola-Lach-Headshot-1-681x1024.jpg 681w, https:\/\/progressions.prsa.org\/wp-content\/uploads\/2025\/08\/Mariola-Lach-Headshot-1-200x300.jpg 200w, https:\/\/progressions.prsa.org\/wp-content\/uploads\/2025\/08\/Mariola-Lach-Headshot-1-768x1155.jpg 768w, https:\/\/progressions.prsa.org\/wp-content\/uploads\/2025\/08\/Mariola-Lach-Headshot-1-1021x1536.jpg 1021w, https:\/\/progressions.prsa.org\/wp-content\/uploads\/2025\/08\/Mariola-Lach-Headshot-1.jpg 1064w\" sizes=\"(max-width: 681px) 100vw, 681px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Mariola Lach es Ejecutiva de Cuentas en el equipo de Crisis e Issues de Zeno, donde aprovecha su experiencia en relaciones p\u00fablicas y comunicaci\u00f3n de crisis para ayudar a los clientes a enfrentar retiros de productos, relaciones con los medios, desastres naturales, asociaciones y cuestiones geopol\u00edticas.\u200b<\/p>\n\n\n\n<p>Tras casi seis a\u00f1os de carrera en el sector de la geotecnolog\u00eda, Mariola inici\u00f3 su camino en relaciones p\u00fablicas en Reputation Architects, apoyando al equipo de planificaci\u00f3n y respuesta ante crisis. Su experiencia abarca los sectores minorista, ambiental, tecnol\u00f3gico, sin fines de lucro, de atenci\u00f3n m\u00e9dica y de consumo.\u200b<\/p>\n\n\n\n<p>Mariola tiene una licenciatura en Ciencias Ambientales de William Paterson University. Actualmente se desempe\u00f1a como Chair de la Secci\u00f3n de Nuevos Profesionales de PRSA y forma parte de la junta directiva del Distrito Tri-Estatal de PRSA.<\/p>\n<\/div><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Nombre Mariola Lach Cargo&nbsp;&nbsp; Ejecutiva de Cuentas, Crisis e Issues en Zeno Group Rol dentro de la Secci\u00f3n de Nuevos Profesionales de PRSA&nbsp; Chair de la Secci\u00f3n \u00bfQu\u00e9 te inspir\u00f3 a involucrarte con PRSA y c\u00f3mo ha evolucionado tu trayectoria dentro de la organizaci\u00f3n?&nbsp; Cuando comenc\u00e9 mi carrera en relaciones p\u00fablicas, me di cuenta de que a\u00fan hab\u00eda mucho que [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Nombre Mariola Lach Cargo Ejecutiva de Cuentas, Crisis e Issues en Zeno Group Rol dentro de la Secci\u00f3n de Nuevos Profesionales de PRSA Chair de la Secci\u00f3n \u00bfQu\u00e9 te inspir\u00f3 a involucrarte con PRSA y c\u00f3mo ha evolucionado tu trayectoria dentro de la organizaci\u00f3n? Cuando comenc\u00e9 mi carrera en relaciones p\u00fablicas, me di cuenta de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Madeline Emerick\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/progressions.prsa.org\/index.php\/2025\/08\/01\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Progressions - Advancing the Profession and the Future Professional\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Voces de PRSA: Perspectivas de la Secci\u00f3n de Nuevos Profesionales \u2013 Mariola Lach - Progressions\" \/>\n\t\t<meta property=\"og:description\" content=\"Nombre Mariola Lach Cargo Ejecutiva de Cuentas, Crisis e Issues en Zeno Group Rol dentro de la Secci\u00f3n de Nuevos Profesionales de PRSA Chair de la Secci\u00f3n \u00bfQu\u00e9 te inspir\u00f3 a involucrarte con PRSA y c\u00f3mo ha evolucionado tu trayectoria dentro de la organizaci\u00f3n? Cuando comenc\u00e9 mi carrera en relaciones p\u00fablicas, me di cuenta de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/progressions.prsa.org\/index.php\/2025\/08\/01\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-08-01T18:47:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-08-01T18:47:40+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Voces de PRSA: Perspectivas de la Secci\u00f3n de Nuevos Profesionales \u2013 Mariola Lach - Progressions\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Nombre Mariola Lach Cargo Ejecutiva de Cuentas, Crisis e Issues en Zeno Group Rol dentro de la Secci\u00f3n de Nuevos Profesionales de PRSA Chair de la Secci\u00f3n \u00bfQu\u00e9 te inspir\u00f3 a involucrarte con PRSA y c\u00f3mo ha evolucionado tu trayectoria dentro de la organizaci\u00f3n? Cuando comenc\u00e9 mi carrera en relaciones p\u00fablicas, me di cuenta de\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/2025\\\/08\\\/01\\\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\\\/#blogposting\",\"name\":\"Voces de PRSA: Perspectivas de la Secci\\u00f3n de Nuevos Profesionales \\u2013 Mariola Lach - Progressions\",\"headline\":\"Voces de PRSA: Perspectivas de la Secci\\u00f3n de Nuevos Profesionales \\u2013 Mariola Lach\",\"author\":{\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/author\\\/m-emerick-prgmail-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/progressions.prsa.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/PRSSA-Progressions-Blog-Headers-PRSSA-Voices-Insights-From-the-New-Professionals-Section-Mariola-Lach-Spanish-Version.png\",\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/2025\\\/08\\\/01\\\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\\\/#articleImage\",\"width\":2240,\"height\":1260},\"datePublished\":\"2025-08-01T14:47:39-04:00\",\"dateModified\":\"2025-08-01T14:47:40-04:00\",\"inLanguage\":\"en\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/2025\\\/08\\\/01\\\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/2025\\\/08\\\/01\\\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\\\/#webpage\"},\"articleSection\":\"Uncategorized\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/2025\\\/08\\\/01\\\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/progressions.prsa.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progressions.prsa.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Uncategorized\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/category\\\/uncategorized\\\/#listItem\",\"position\":2,\"name\":\"Uncategorized\",\"item\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/category\\\/uncategorized\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/2025\\\/08\\\/01\\\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\\\/#listItem\",\"name\":\"Voces de PRSA: Perspectivas de la Secci\\u00f3n de Nuevos Profesionales \\u2013 Mariola Lach\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/progressions.prsa.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/2025\\\/08\\\/01\\\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\\\/#listItem\",\"position\":3,\"name\":\"Voces de PRSA: Perspectivas de la Secci\\u00f3n de Nuevos Profesionales \\u2013 Mariola Lach\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Uncategorized\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/#organization\",\"name\":\"Progressions\",\"description\":\"Advancing the Profession and the Future Professional\",\"url\":\"https:\\\/\\\/progressions.prsa.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/author\\\/m-emerick-prgmail-com\\\/#author\",\"url\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/author\\\/m-emerick-prgmail-com\\\/\",\"name\":\"Madeline Emerick\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/2025\\\/08\\\/01\\\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5d802a62a384e03b66ab11cd848c631?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Madeline Emerick\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/2025\\\/08\\\/01\\\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\\\/#webpage\",\"url\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/2025\\\/08\\\/01\\\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\\\/\",\"name\":\"Voces de PRSA: Perspectivas de la Secci\\u00f3n de Nuevos Profesionales \\u2013 Mariola Lach - Progressions\",\"description\":\"Nombre Mariola Lach Cargo Ejecutiva de Cuentas, Crisis e Issues en Zeno Group Rol dentro de la Secci\\u00f3n de Nuevos Profesionales de PRSA Chair de la Secci\\u00f3n \\u00bfQu\\u00e9 te inspir\\u00f3 a involucrarte con PRSA y c\\u00f3mo ha evolucionado tu trayectoria dentro de la organizaci\\u00f3n? Cuando comenc\\u00e9 mi carrera en relaciones p\\u00fablicas, me di cuenta de\",\"inLanguage\":\"en\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/2025\\\/08\\\/01\\\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/author\\\/m-emerick-prgmail-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/index.php\\\/author\\\/m-emerick-prgmail-com\\\/#author\"},\"datePublished\":\"2025-08-01T14:47:39-04:00\",\"dateModified\":\"2025-08-01T14:47:40-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/#website\",\"url\":\"https:\\\/\\\/progressions.prsa.org\\\/\",\"name\":\"Progressions\",\"description\":\"Advancing the Profession and the Future Professional\",\"inLanguage\":\"en\",\"publisher\":{\"@id\":\"https:\\\/\\\/progressions.prsa.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Voces de PRSA: Perspectivas de la Secci\u00f3n de Nuevos Profesionales \u2013 Mariola Lach - Progressions","description":"Nombre Mariola Lach Cargo Ejecutiva de Cuentas, Crisis e Issues en Zeno Group Rol dentro de la Secci\u00f3n de Nuevos Profesionales de PRSA Chair de la Secci\u00f3n \u00bfQu\u00e9 te inspir\u00f3 a involucrarte con PRSA y c\u00f3mo ha evolucionado tu trayectoria dentro de la organizaci\u00f3n? Cuando comenc\u00e9 mi carrera en relaciones p\u00fablicas, me di cuenta de","canonical_url":"https:\/\/progressions.prsa.org\/index.php\/2025\/08\/01\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/progressions.prsa.org\/index.php\/2025\/08\/01\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\/#blogposting","name":"Voces de PRSA: Perspectivas de la Secci\u00f3n de Nuevos Profesionales \u2013 Mariola Lach - Progressions","headline":"Voces de PRSA: Perspectivas de la Secci\u00f3n de Nuevos Profesionales \u2013 Mariola Lach","author":{"@id":"https:\/\/progressions.prsa.org\/index.php\/author\/m-emerick-prgmail-com\/#author"},"publisher":{"@id":"https:\/\/progressions.prsa.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/progressions.prsa.org\/wp-content\/uploads\/2025\/08\/PRSSA-Progressions-Blog-Headers-PRSSA-Voices-Insights-From-the-New-Professionals-Section-Mariola-Lach-Spanish-Version.png","@id":"https:\/\/progressions.prsa.org\/index.php\/2025\/08\/01\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\/#articleImage","width":2240,"height":1260},"datePublished":"2025-08-01T14:47:39-04:00","dateModified":"2025-08-01T14:47:40-04:00","inLanguage":"en","mainEntityOfPage":{"@id":"https:\/\/progressions.prsa.org\/index.php\/2025\/08\/01\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\/#webpage"},"isPartOf":{"@id":"https:\/\/progressions.prsa.org\/index.php\/2025\/08\/01\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\/#webpage"},"articleSection":"Uncategorized"},{"@type":"BreadcrumbList","@id":"https:\/\/progressions.prsa.org\/index.php\/2025\/08\/01\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/progressions.prsa.org#listItem","position":1,"name":"Home","item":"https:\/\/progressions.prsa.org","nextItem":{"@type":"ListItem","@id":"https:\/\/progressions.prsa.org\/index.php\/category\/uncategorized\/#listItem","name":"Uncategorized"}},{"@type":"ListItem","@id":"https:\/\/progressions.prsa.org\/index.php\/category\/uncategorized\/#listItem","position":2,"name":"Uncategorized","item":"https:\/\/progressions.prsa.org\/index.php\/category\/uncategorized\/","nextItem":{"@type":"ListItem","@id":"https:\/\/progressions.prsa.org\/index.php\/2025\/08\/01\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\/#listItem","name":"Voces de PRSA: Perspectivas de la Secci\u00f3n de Nuevos Profesionales \u2013 Mariola Lach"},"previousItem":{"@type":"ListItem","@id":"https:\/\/progressions.prsa.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/progressions.prsa.org\/index.php\/2025\/08\/01\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\/#listItem","position":3,"name":"Voces de PRSA: Perspectivas de la Secci\u00f3n de Nuevos Profesionales \u2013 Mariola Lach","previousItem":{"@type":"ListItem","@id":"https:\/\/progressions.prsa.org\/index.php\/category\/uncategorized\/#listItem","name":"Uncategorized"}}]},{"@type":"Organization","@id":"https:\/\/progressions.prsa.org\/#organization","name":"Progressions","description":"Advancing the Profession and the Future Professional","url":"https:\/\/progressions.prsa.org\/"},{"@type":"Person","@id":"https:\/\/progressions.prsa.org\/index.php\/author\/m-emerick-prgmail-com\/#author","url":"https:\/\/progressions.prsa.org\/index.php\/author\/m-emerick-prgmail-com\/","name":"Madeline Emerick","image":{"@type":"ImageObject","@id":"https:\/\/progressions.prsa.org\/index.php\/2025\/08\/01\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/f5d802a62a384e03b66ab11cd848c631?s=96&d=mm&r=g","width":96,"height":96,"caption":"Madeline Emerick"}},{"@type":"WebPage","@id":"https:\/\/progressions.prsa.org\/index.php\/2025\/08\/01\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\/#webpage","url":"https:\/\/progressions.prsa.org\/index.php\/2025\/08\/01\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\/","name":"Voces de PRSA: Perspectivas de la Secci\u00f3n de Nuevos Profesionales \u2013 Mariola Lach - Progressions","description":"Nombre Mariola Lach Cargo Ejecutiva de Cuentas, Crisis e Issues en Zeno Group Rol dentro de la Secci\u00f3n de Nuevos Profesionales de PRSA Chair de la Secci\u00f3n \u00bfQu\u00e9 te inspir\u00f3 a involucrarte con PRSA y c\u00f3mo ha evolucionado tu trayectoria dentro de la organizaci\u00f3n? Cuando comenc\u00e9 mi carrera en relaciones p\u00fablicas, me di cuenta de","inLanguage":"en","isPartOf":{"@id":"https:\/\/progressions.prsa.org\/#website"},"breadcrumb":{"@id":"https:\/\/progressions.prsa.org\/index.php\/2025\/08\/01\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\/#breadcrumblist"},"author":{"@id":"https:\/\/progressions.prsa.org\/index.php\/author\/m-emerick-prgmail-com\/#author"},"creator":{"@id":"https:\/\/progressions.prsa.org\/index.php\/author\/m-emerick-prgmail-com\/#author"},"datePublished":"2025-08-01T14:47:39-04:00","dateModified":"2025-08-01T14:47:40-04:00"},{"@type":"WebSite","@id":"https:\/\/progressions.prsa.org\/#website","url":"https:\/\/progressions.prsa.org\/","name":"Progressions","description":"Advancing the Profession and the Future Professional","inLanguage":"en","publisher":{"@id":"https:\/\/progressions.prsa.org\/#organization"}}]},"og:locale":"en_US","og:site_name":"Progressions - Advancing the Profession and the Future Professional","og:type":"article","og:title":"Voces de PRSA: Perspectivas de la Secci\u00f3n de Nuevos Profesionales \u2013 Mariola Lach - Progressions","og:description":"Nombre Mariola Lach Cargo Ejecutiva de Cuentas, Crisis e Issues en Zeno Group Rol dentro de la Secci\u00f3n de Nuevos Profesionales de PRSA Chair de la Secci\u00f3n \u00bfQu\u00e9 te inspir\u00f3 a involucrarte con PRSA y c\u00f3mo ha evolucionado tu trayectoria dentro de la organizaci\u00f3n? Cuando comenc\u00e9 mi carrera en relaciones p\u00fablicas, me di cuenta de","og:url":"https:\/\/progressions.prsa.org\/index.php\/2025\/08\/01\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\/","article:published_time":"2025-08-01T18:47:39+00:00","article:modified_time":"2025-08-01T18:47:40+00:00","twitter:card":"summary_large_image","twitter:title":"Voces de PRSA: Perspectivas de la Secci\u00f3n de Nuevos Profesionales \u2013 Mariola Lach - Progressions","twitter:description":"Nombre Mariola Lach Cargo Ejecutiva de Cuentas, Crisis e Issues en Zeno Group Rol dentro de la Secci\u00f3n de Nuevos Profesionales de PRSA Chair de la Secci\u00f3n \u00bfQu\u00e9 te inspir\u00f3 a involucrarte con PRSA y c\u00f3mo ha evolucionado tu trayectoria dentro de la organizaci\u00f3n? Cuando comenc\u00e9 mi carrera en relaciones p\u00fablicas, me di cuenta de"},"aioseo_meta_data":{"post_id":"13585","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-08-01 18:47:40","updated":"2025-11-05 02:24:37","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/progressions.prsa.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/progressions.prsa.org\/index.php\/category\/uncategorized\/\" title=\"Uncategorized\">Uncategorized<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tVoces de PRSA: Perspectivas de la Secci\u00f3n de Nuevos Profesionales \u2013 Mariola Lach\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/progressions.prsa.org"},{"label":"Uncategorized","link":"https:\/\/progressions.prsa.org\/index.php\/category\/uncategorized\/"},{"label":"Voces de PRSA: Perspectivas de la Secci\u00f3n de Nuevos Profesionales \u2013 Mariola Lach","link":"https:\/\/progressions.prsa.org\/index.php\/2025\/08\/01\/voces-de-prsa-perspectivas-de-la-seccion-de-nuevos-profesionales-mariola-lach\/"}],"_links":{"self":[{"href":"https:\/\/progressions.prsa.org\/index.php\/wp-json\/wp\/v2\/posts\/13585"}],"collection":[{"href":"https:\/\/progressions.prsa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progressions.prsa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progressions.prsa.org\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/progressions.prsa.org\/index.php\/wp-json\/wp\/v2\/comments?post=13585"}],"version-history":[{"count":1,"href":"https:\/\/progressions.prsa.org\/index.php\/wp-json\/wp\/v2\/posts\/13585\/revisions"}],"predecessor-version":[{"id":13588,"href":"https:\/\/progressions.prsa.org\/index.php\/wp-json\/wp\/v2\/posts\/13585\/revisions\/13588"}],"wp:attachment":[{"href":"https:\/\/progressions.prsa.org\/index.php\/wp-json\/wp\/v2\/media?parent=13585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progressions.prsa.org\/index.php\/wp-json\/wp\/v2\/categories?post=13585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progressions.prsa.org\/index.php\/wp-json\/wp\/v2\/tags?post=13585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}